{"id":13657,"date":"2023-06-10T15:12:46","date_gmt":"2023-06-10T15:12:46","guid":{"rendered":"https:\/\/dincarchitect.com\/?post_type=portfolio&#038;p=13657"},"modified":"2023-06-23T11:36:44","modified_gmt":"2023-06-23T11:36:44","slug":"aumetz-les-cypres","status":"publish","type":"portfolio","link":"https:\/\/dincarchitect.com\/nl\/projects\/aumetz-les-cypres\/","title":{"rendered":"Aumetz \u2013 Les Cypr\u00e8s"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539257570946\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1778678957\" data-ride=\"vc_carousel\" data-wrap=\"false\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><ol class=\"vc_carousel-indicators\"><li data-target=\"#vc_images-carousel-1-1778678957\" data-slide-to=\"0\"><\/li><li data-target=\"#vc_images-carousel-1-1778678957\" data-slide-to=\"1\"><\/li><li data-target=\"#vc_images-carousel-1-1778678957\" data-slide-to=\"2\"><\/li><\/ol><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1-1024x576.jpg\" data-lightbox=\"lightbox[rel-13657-1870519585]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1.jpg\" class=\"attachment-full\" alt=\"\" title=\"aumetz-1\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop1-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2-1024x576.jpg\" data-lightbox=\"lightbox[rel-13657-1870519585]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2.jpg\" class=\"attachment-full\" alt=\"\" title=\"aumetz-2\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop2-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3-1024x576.jpg\" data-lightbox=\"lightbox[rel-13657-1870519585]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3.jpg\" class=\"attachment-full\" alt=\"\" title=\"aumetz-3\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/shop3-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-1-1778678957\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-1-1778678957\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1535984209309\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><span class=\"subtitle dash-false style-dark text-default\">Architectuur<\/span>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Aumetz \u2013 Les Cypr\u00e8s<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"dash style-dark default\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Informatie<\/h4>\n<div style=\"text-align: justify;\">\n<p>Aumetz \u2013 Les Cypr\u00e8s profiteert van een ideale omgeving voor het dagelijks leven. Het vastgoedcomplex, bestaande uit een residentie met 21 wooneenheden, kenmerkt zich door een eigentijdse en harmonieuze architectuur die u zal boeien met zijn toplocaties en hoogwaardige voorzieningen.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><span style=\"color: #ffffff;\">Informatie<\/span><\/h4>\n<div style=\"text-align: justify;\">\n<p>Elke woning komt uit op prachtige buitenruimtes, waaronder een tuin, balkon, loggia, terras en biedt een prachtig vrij uitzicht.<\/p>\n<p>Ga voor meer informatie naar <a href=\"https:\/\/dincarchitect.com\/nl\/\" target=\"_new\" rel=\"noopener\">www.dincarchitect.com<\/a>.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Datum<\/strong><\/td><td> augustus 2021<\/td><\/tr><td><strong> Plaats<\/strong><\/td><td> Frankrijk<\/td><\/tr><td> <strong>Klant<\/strong><\/td><td> -<\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Kosten<\/strong><\/td><td> -<\/td><\/tr><td> <strong>Oppervlak<\/td><td> <\/strong>18000m2<\/td><\/tr><td> <strong>Categorie<\/td><td><\/strong> Huisvesting <\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Architectuur Aumetz \u2013 Les Cypr\u00e8s Informatie Aumetz - Les Cypr\u00e8s profiteert van een ideale omgeving voor het dagelijks leven. Het vastgoedcomplex, bestaande uit een residentie met 21 wooneenheden, beschikt over een eigentijdse en harmonieuze architectuur die u zal fascineren met zijn toplocaties en hoogwaardige voorzieningen. Informatie Elke woning biedt toegang tot prachtige buitenruimtes, waaronder [...]","protected":false},"author":1,"featured_media":14631,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio_category":[49],"portfolio_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/portfolio\/13657"}],"collection":[{"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/comments?post=13657"}],"version-history":[{"count":0,"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/portfolio\/13657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/media\/14631"}],"wp:attachment":[{"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/media?parent=13657"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/portfolio_category?post=13657"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/dincarchitect.com\/nl\/wp-json\/wp\/v2\/portfolio_tag?post=13657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}