{"id":14717,"date":"2023-06-18T06:36:03","date_gmt":"2023-06-18T06:36:03","guid":{"rendered":"https:\/\/dincarchitect.com\/?post_type=portfolio&#038;p=14717"},"modified":"2023-06-24T07:41:45","modified_gmt":"2023-06-24T07:41:45","slug":"living-room-dinner","status":"publish","type":"portfolio","link":"https:\/\/dincarchitect.com\/it\/projects\/living-room-1-2\/","title":{"rendered":"Cena in soggiorno"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539257570946\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1778671878\" data-ride=\"vc_carousel\" data-wrap=\"false\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><ol class=\"vc_carousel-indicators\"><li data-target=\"#vc_images-carousel-1-1778671878\" data-slide-to=\"0\"><\/li><li data-target=\"#vc_images-carousel-1-1778671878\" data-slide-to=\"1\"><\/li><li data-target=\"#vc_images-carousel-1-1778671878\" data-slide-to=\"2\"><\/li><li data-target=\"#vc_images-carousel-1-1778671878\" data-slide-to=\"3\"><\/li><li data-target=\"#vc_images-carousel-1-1778671878\" data-slide-to=\"4\"><\/li><\/ol><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5-1024x576.jpeg\" data-lightbox=\"lightbox[rel-14717-3717973036]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5.jpeg\" class=\"attachment-full\" alt=\"\" title=\"soggiorno\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5.jpeg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5-1024x576.jpeg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5-768x432.jpeg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5-1536x864.jpeg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d5-18x10.jpeg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4-1024x576.jpeg\" data-lightbox=\"lightbox[rel-14717-3717973036]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4.jpeg\" class=\"attachment-full\" alt=\"\" title=\"soggiorno\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4.jpeg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4-1024x576.jpeg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4-768x432.jpeg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4-1536x864.jpeg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d4-18x10.jpeg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1-1024x576.jpeg\" data-lightbox=\"lightbox[rel-14717-3717973036]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1.jpeg\" class=\"attachment-full\" alt=\"\" title=\"soggiorno\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1.jpeg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1-1024x576.jpeg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1-768x432.jpeg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1-1536x864.jpeg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d3-1-18x10.jpeg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1-1024x576.jpeg\" data-lightbox=\"lightbox[rel-14717-3717973036]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1.jpeg\" class=\"attachment-full\" alt=\"\" title=\"soggiorno\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1.jpeg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1-1024x576.jpeg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1-768x432.jpeg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1-1536x864.jpeg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d2-1-18x10.jpeg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1-1024x576.jpeg\" data-lightbox=\"lightbox[rel-14717-3717973036]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1.jpeg\" class=\"attachment-full\" alt=\"\" title=\"soggiorno\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1.jpeg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1-1024x576.jpeg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1-768x432.jpeg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1-1536x864.jpeg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/d1-1-18x10.jpeg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-1-1778671878\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-1-1778671878\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1535984209309\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><span class=\"subtitle dash-false style-dark text-default\">Interior design<\/span>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-&#091;#444654&#093;\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-&#091;38rem&#093; xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-&#091;calc(100%-50px)&#093; flex-col gap-1 md:gap-3 lg:w-&#091;calc(100%-115px)&#093;\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-&#091;20px&#093; flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2>Soggiorno \u2013 Cena<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"dash style-dark default\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Informazione<\/h4>\n<div style=\"text-align: justify;\">\n<p>Siamo entusiasti di presentarti un&#039;anteprima del nostro ultimo progetto personalizzato: una splendida cena in salone. Prima che il nostro cliente iniziasse la costruzione, abbiamo creato un rendering interno per visualizzare il soggiorno completato. Il nostro cliente ci ha fornito tutti i dettagli del progetto necessari e i risultati sono davvero sorprendenti!<\/p>\n<p>Con l&#039;aiuto di questa rappresentazione 3D, siamo riusciti a progettare meticolosamente ogni dettaglio del futuro soggiorno, dalla scelta delle piastrelle agli elementi decorativi, garantendo uno spazio funzionale ed esteticamente gradevole.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><span style=\"color: #ffffff;\">Informazione<\/span><\/h4>\n<div style=\"text-align: justify;\">\n<p>Questo rendering interno ci ha permesso di prendere decisioni informate e di collaborare strettamente con il nostro team di costruzione, garantendo un&#039;esecuzione ottimale. Abbiamo piena fiducia che questo soggiorno diventer\u00e0 una vera oasi di relax e comfort.<\/p>\n<p>Non esitate a contattarci per ulteriori informazioni sul nostro processo di costruzione o se avete domande sui nostri servizi. Siamo qui per assisterti e saremo lieti di aiutarti. #soggiorno #rendering interno #processo di costruzione<\/p>\n<p>Per ulteriori informazioni, si prega di contattarci.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Data<\/strong><\/td><td> gennaio 2023<\/td><\/tr><td><strong> Posizione<\/strong><\/td><td>  Francia<\/td><\/tr><td> <strong>Cliente<\/strong><\/td><td> GG <\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Costo<\/strong><\/td><td> -<\/td><\/tr><td> <strong>Superficie<\/td><td> <\/strong>30m2<\/td><\/tr><td> <strong>Categoria<\/td><td><\/strong> Soggiorno<\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Soggiorno con design d&#039;interni - Informazioni sulla cena Siamo entusiasti di presentarvi un&#039;anteprima del nostro ultimo progetto personalizzato: una splendida cena in salone. Prima che il nostro cliente iniziasse la costruzione, abbiamo creato un rendering interno per visualizzare il soggiorno completato. Il nostro cliente ci ha fornito tutti i dettagli necessari del progetto e [...]","protected":false},"author":1,"featured_media":14716,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio_category":[36],"portfolio_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio\/14717"}],"collection":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/comments?post=14717"}],"version-history":[{"count":0,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio\/14717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/media\/14716"}],"wp:attachment":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/media?parent=14717"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio_category?post=14717"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio_tag?post=14717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}