{"id":13663,"date":"2023-06-10T15:26:02","date_gmt":"2023-06-10T15:26:02","guid":{"rendered":"https:\/\/dincarchitect.com\/?post_type=portfolio&#038;p=13663"},"modified":"2023-06-23T13:48:53","modified_gmt":"2023-06-23T13:48:53","slug":"hettange","status":"publish","type":"portfolio","link":"https:\/\/dincarchitect.com\/it\/projects\/hettange\/","title":{"rendered":"Hettange"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539257570946\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1778673892\" data-ride=\"vc_carousel\" data-wrap=\"false\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><ol class=\"vc_carousel-indicators\"><li data-target=\"#vc_images-carousel-1-1778673892\" data-slide-to=\"0\"><\/li><li data-target=\"#vc_images-carousel-1-1778673892\" data-slide-to=\"1\"><\/li><li data-target=\"#vc_images-carousel-1-1778673892\" data-slide-to=\"2\"><\/li><li data-target=\"#vc_images-carousel-1-1778673892\" data-slide-to=\"3\"><\/li><\/ol><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4-1024x576.jpg\" data-lightbox=\"lightbox[rel-13663-2450484539]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4.jpg\" class=\"attachment-full\" alt=\"\" title=\"hettange4\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange4-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3-1024x576.jpg\" data-lightbox=\"lightbox[rel-13663-2450484539]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3.jpg\" class=\"attachment-full\" alt=\"\" title=\"hettange3\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange3-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1-1024x576.jpg\" data-lightbox=\"lightbox[rel-13663-2450484539]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1.jpg\" class=\"attachment-full\" alt=\"\" title=\"hettange1\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange1-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2-1024x576.jpg\" data-lightbox=\"lightbox[rel-13663-2450484539]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2.jpg\" class=\"attachment-full\" alt=\"\" title=\"hettange2\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/hettange2-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-1-1778673892\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-1-1778673892\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1535984209309\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><span class=\"subtitle dash-false style-dark text-default\">Architettura<\/span>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-&#091;#444654&#093;\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-&#091;38rem&#093; xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-&#091;calc(100%-50px)&#093; flex-col gap-1 md:gap-3 lg:w-&#091;calc(100%-115px)&#093;\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-&#091;20px&#093; flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2>Hettange<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"dash style-dark default\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Informazione<\/h4>\n<div style=\"text-align: justify;\">\n<p>Hettange gode di un ambiente ideale per la vita quotidiana. Questo complesso immobiliare, composto da un residence di 21 unit\u00e0, presenta un&#039;architettura contemporanea e armoniosa che ti attirer\u00e0 con le sue posizioni privilegiate e i servizi di alto livello.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><span style=\"color: #ffffff;\">Informazione<\/span><\/h4>\n<div style=\"text-align: justify;\">\n<p>Ogni propriet\u00e0 si apre su splendidi spazi esterni, tra cui giardino, balcone, loggia, terrazza e offre splendide viste senza ostacoli.<\/p>\n<p>Per maggiori informazioni per favore visita <a href=\"https:\/\/dincarchitect.com\/it\/\" target=\"_new\" rel=\"noopener\">www.dincarchitect.com<\/a>.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Data<\/strong><\/td><td> giugno 2021<\/td><\/tr><td><strong> Posizione<\/strong><\/td><td> Francia<\/td><\/tr><td> <strong>Cliente<\/strong><\/td><td> <\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Costo<\/strong><\/td><td> -<\/td><\/tr><td> <strong>Superficie<\/td><td> <\/strong>16000 mq<\/td><\/tr><td> <strong>Categoria<\/td><td><\/strong> Alloggio Villa Casa <\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Architettura Hettange Informazioni Hettange gode di un ambiente ideale per la vita quotidiana. Questo complesso immobiliare, composto da una residenza di 21 unit\u00e0, presenta un&#039;architettura contemporanea e armoniosa che vi sedurr\u00e0 con la sua posizione privilegiata e servizi di alto livello. Informazioni Ogni propriet\u00e0 si apre su splendidi spazi esterni, tra cui giardino, balcone, loggia, terrazza, e offre splendide viste senza ostacoli [...]","protected":false},"author":1,"featured_media":14649,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio_category":[49],"portfolio_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio\/13663"}],"collection":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/comments?post=13663"}],"version-history":[{"count":0,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio\/13663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/media\/14649"}],"wp:attachment":[{"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/media?parent=13663"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio_category?post=13663"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/dincarchitect.com\/it\/wp-json\/wp\/v2\/portfolio_tag?post=13663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}