{"id":14740,"date":"2023-06-20T04:00:13","date_gmt":"2023-06-20T04:00:13","guid":{"rendered":"https:\/\/dincarchitect.com\/?post_type=portfolio&#038;p=14740"},"modified":"2023-06-23T13:55:40","modified_gmt":"2023-06-23T13:55:40","slug":"villa-jum","status":"publish","type":"portfolio","link":"https:\/\/dincarchitect.com\/es\/projects\/villa-jum\/","title":{"rendered":"villa jum"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539257570946\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1778676398\" data-ride=\"vc_carousel\" data-wrap=\"false\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><ol class=\"vc_carousel-indicators\"><li data-target=\"#vc_images-carousel-1-1778676398\" data-slide-to=\"0\"><\/li><li data-target=\"#vc_images-carousel-1-1778676398\" data-slide-to=\"1\"><\/li><li data-target=\"#vc_images-carousel-1-1778676398\" data-slide-to=\"2\"><\/li><li data-target=\"#vc_images-carousel-1-1778676398\" data-slide-to=\"3\"><\/li><\/ol><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3-1024x576.jpg\" data-lightbox=\"lightbox[rel-14740-976667581]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3.jpg\" class=\"attachment-full\" alt=\"\" title=\"villa-jum-3\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-3-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4-1024x576.jpg\" data-lightbox=\"lightbox[rel-14740-976667581]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4.jpg\" class=\"attachment-full\" alt=\"\" title=\"villa-jum-4\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-4-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2-1024x576.jpg\" data-lightbox=\"lightbox[rel-14740-976667581]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2.jpg\" class=\"attachment-full\" alt=\"\" title=\"villa-jum-2\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-2-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1-1024x576.jpg\" data-lightbox=\"lightbox[rel-14740-976667581]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"villa-jum-1\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/villa-jum-1-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-1-1778676398\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-1-1778676398\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1535984209309\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><span class=\"subtitle dash-false style-dark text-default\">Arquitectura<\/span>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-&#091;#444654&#093;\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-&#091;38rem&#093; xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-&#091;calc(100%-50px)&#093; flex-col gap-1 md:gap-3 lg:w-&#091;calc(100%-115px)&#093;\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-&#091;20px&#093; flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2>villa jum<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"dash style-dark default\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Informaci\u00f3n<\/h4>\n<div style=\"text-align: justify;\">\n<p>Descubra nuestro \u00faltimo proyecto exterior: \u00a1una impresionante representaci\u00f3n en 3D! Antes de que nuestro cliente comience la construcci\u00f3n, creamos una visualizaci\u00f3n detallada del proyecto terminado, incorporando elementos como opciones de ventanas y materiales exteriores. Cada aspecto fue cuidadosamente estudiado para proporcionar un espacio que sea a la vez funcional y est\u00e9tico.<\/p>\n<p>Esta representaci\u00f3n fue crucial para tomar decisiones informadas y colaborar de cerca con nuestro equipo de construcci\u00f3n, asegurando una ejecuci\u00f3n \u00f3ptima. Estamos seguros de que este proyecto se convertir\u00e1 en una verdadera referencia para nosotros.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><span style=\"color: #ffffff;\">Informaci\u00f3n<\/span><\/h4>\n<div style=\"text-align: justify;\">\n<p>No dude en contactarnos para obtener m\u00e1s informaci\u00f3n sobre nuestro proceso de construcci\u00f3n o para hacer cualquier pregunta sobre nuestros servicios. Estaremos encantados de atenderte. 1TP5Proyecto de textura #3Drenderizado #construcci\u00f3n #Visualizaci\u00f3n #arquitectura<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n, no dude en comunicarse con nosotros.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Fecha<\/strong><\/td><td> marzo 2023<\/td><\/tr><td><strong> Ubicaci\u00f3n<\/strong><\/td><td> Pa\u00edses Bajos<\/td><\/tr><td> <strong>Cliente<\/strong><\/td><td> EE. UU.<\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Costo<\/strong><\/td><td> -<\/td><\/tr><td> <strong>Superficie<\/td><td> <\/strong>-<\/td><\/tr><td> <strong>Categor\u00eda<\/td><td><\/strong> Alojamiento<\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Architecture Villa Jum Information Discover our latest exterior project: a stunning 3D rendering! Before our client begins the construction, we created a detailed visualization of the finished project, incorporating elements such as window choices and exterior materials. Every aspect was carefully studied to provide a space that is both functional and aesthetic. This rendering was [...]","protected":false},"author":1,"featured_media":14752,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio_category":[49],"portfolio_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio\/14740"}],"collection":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/comments?post=14740"}],"version-history":[{"count":0,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio\/14740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/media\/14752"}],"wp:attachment":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/media?parent=14740"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=14740"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio_tag?post=14740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}