{"id":13669,"date":"2023-06-10T15:37:43","date_gmt":"2023-06-10T15:37:43","guid":{"rendered":"https:\/\/dincarchitect.com\/?post_type=portfolio&#038;p=13669"},"modified":"2023-06-23T13:52:26","modified_gmt":"2023-06-23T13:52:26","slug":"mozaik","status":"publish","type":"portfolio","link":"https:\/\/dincarchitect.com\/es\/projects\/mozaik\/","title":{"rendered":"Mozaik"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539257570946\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1778671817\" data-ride=\"vc_carousel\" data-wrap=\"false\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><ol class=\"vc_carousel-indicators\"><li data-target=\"#vc_images-carousel-1-1778671817\" data-slide-to=\"0\"><\/li><li data-target=\"#vc_images-carousel-1-1778671817\" data-slide-to=\"1\"><\/li><\/ol><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1-1024x576.jpg\" data-lightbox=\"lightbox[rel-13669-4140238121]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"yutz-1\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-1-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2-1024x576.jpg\" data-lightbox=\"lightbox[rel-13669-4140238121]\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2.jpg\" class=\"attachment-full\" alt=\"\" title=\"yutz-2\" srcset=\"https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2.jpg 1920w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2-1024x576.jpg 1024w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2-768x432.jpg 768w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2-1536x864.jpg 1536w, https:\/\/dincarchitect.com\/wp-content\/uploads\/2023\/06\/yutz-2-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-1-1778671817\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-1-1778671817\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1535984209309\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><span class=\"subtitle dash-false style-dark text-default\">Arquitectura<\/span>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-&#091;#444654&#093;\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-&#091;38rem&#093; xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-&#091;calc(100%-50px)&#093; flex-col gap-1 md:gap-3 lg:w-&#091;calc(100%-115px)&#093;\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-&#091;20px&#093; flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2>Mozaik<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"dash style-dark default\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Informaci\u00f3n<\/h4>\n<div style=\"text-align: justify;\">\n<p>Hemos dise\u00f1ado el proyecto Mosaik para una empresa en Francia. Este proyecto ha sido totalmente adaptado a las especificaciones del cliente. Le agradecemos por elegirnos. Esperamos ventas exitosas y un resultado pr\u00f3spero para el proyecto.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4><span style=\"color: #ffffff;\">Informaci\u00f3n<\/span><\/h4>\n<div style=\"text-align: justify;\">\n<p>Para mayor informaci\u00f3n por favor visite <a href=\"https:\/\/dincarchitect.com\/es\/\" target=\"_new\" rel=\"noopener\">www.dincarchitect.com<\/a>.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Fecha<\/strong><\/td><td> junio 2021<\/td><\/tr><td><strong> Ubicaci\u00f3n<\/strong><\/td><td> Francia<\/td><\/tr><td> <strong>Cliente<\/strong><\/td><td> Mozaik <\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table class=\"default\"><tbody><tr><th> <\/th><th> <\/th><\/tr><tr><td><strong>Costo<\/strong><\/td><td> -<\/td><\/tr><td> <strong>Superficie<\/td><td> <\/strong>-<\/td><\/tr><td> <strong>Categor\u00eda<\/td><td><\/strong> Alojamiento<\/td><\/tr><\/tbody><\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Arquitectura Mozaik Informaci\u00f3n Hemos dise\u00f1ado el proyecto Mosaik para una empresa en Francia. Este proyecto ha sido totalmente personalizado seg\u00fan las especificaciones del cliente. Le agradecemos que nos haya elegido. Esperamos ventas exitosas y un resultado pr\u00f3spero para el proyecto. Informaci\u00f3n Para obtener m\u00e1s informaci\u00f3n, visite www.dincarchitect.com. Fecha Junio 2021 Ubicaci\u00f3n Francia Cliente [...]","protected":false},"author":1,"featured_media":14657,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio_category":[49],"portfolio_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio\/13669"}],"collection":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/comments?post=13669"}],"version-history":[{"count":0,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio\/13669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/media\/14657"}],"wp:attachment":[{"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/media?parent=13669"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=13669"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/dincarchitect.com\/es\/wp-json\/wp\/v2\/portfolio_tag?post=13669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}